{"id":52625,"date":"2021-10-13T13:55:30","date_gmt":"2021-10-13T11:55:30","guid":{"rendered":"https:\/\/www.studiogiochi.com\/backgammon\/citta-di-jesolo\/"},"modified":"2023-10-09T17:58:33","modified_gmt":"2023-10-09T15:58:33","slug":"citta-di-jesolo","status":"publish","type":"page","link":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/","title":{"rendered":"Citt\u00e0 di Jesolo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column width=&#8221;1\/4&#8243; el_class=&#8221;download&#8221;][vc_single_image image=&#8221;3342&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_tta_tabs][vc_tta_section title=&#8221;Citt\u00e0 di Jesolo&#8221; tab_id=&#8221;citta-di-jesolo&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>23rd CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: left;\">In the setting of the Hotel Atlantico in Jesolo Lido (VE), the <strong>23rd City of Jesolo International Backgammon Tournament<\/strong> was held from 27 September to 1 October 2023. It was masterfully organised and directed by our Dario Zaccariotto, CNB national councillor, together with his colleagues Alfonso Sara and Cesare Nanti.<\/p>\n<p style=\"text-align: justify;\">The event was organised by the <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB \u2013 Circuito Nazionale Backgammon<\/a> in collaboration with Backgammon Club Venezia, Hotel Atlantico and ACSI &#8211; Associazione Centri Sportivi Italiani, and is also valid as the penultimate stage of the 2023 Circuit.<\/p>\n<p style=\"text-align: justify;\">There were many opportunities for enthusiasts: in addition to the tournament in three categories (Champion played with direct elimination in the &#8216;double chance&#8217; version, Intermediate with the Italo-Swiss formula, and Amateur for those who are just starting out in competitive play) there was the team tournament, the doubles tournament, the sparkling Swing, the speed tournament with tight time limits, and more. The rich schedule was appreciated by the players who flocked to Jesolo in large numbers: over 120 backgammon players threw dice on the sunny Adriatic beach for the penultimate stage of the 2023 National Circuit. Worth mentioning is the fact that people from over 20 countries, including Costa Rica, Australia and the United States, attended the tournament.<\/p>\n<p style=\"text-align: justify;\">But let us come to the record: the main tournament was won by Philippe Vouh\u00e9 from France over Antonio Anelli from Pesaro, with a score of 15 to 3. For the histrionic Frenchman also a place of honour in the speed tournament. The French were also victorious thanks to Kader Turk, who won the Open tournament, and Fraderic Bonard, who won the swing.<br \/>\nBulgarian victory in the pairs tournament, in which Nikolay Dragostinov and Atanas Tachev got the better of Laurence Sinitky and Jiri Vala, while a transnational team triumphed in the team tournament in which our Venetian team leaders Sergio Fragiacomo (captain), Massimo Trov\u00f2 and Dario De Toffoli bowed out only to the winners Sebastian Wilkinson (UK), Ricardo Malas (Spain) and Mahmoud Taha (Austria).<\/p>\n<p style=\"text-align: justify;\">Little glory for the leader of the ranking, Andrea de Zandonati from Mestre, who, despite the setback, still leads heading into the last tournament of the season.<\/p>\n<p style=\"text-align: justify;\">Now, the appointment is set for Lago di Como, where the final stage of the championship will take place in Varenna from 27 to 29 October, and Montegrotto, where the final playoffs will be held from 30 November to 3 December.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2023\/10\/Depliant_Jesolo_2023.jpg\" rel=\"lightbox[52625]\"><strong>Event schedule<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2023\/10\/Risultati-Backgammon-Jesolo-2023.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Results of the main tournaments in PDF<\/strong><\/a><\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761277-8c7933a7-05c4-0&#8243; include=&#8221;69234,69236,69238,69240,69242,69246,69248,69251,69253,69255,69257,69259,69261,69263,69265,69267,69269,69271,69273,69275,69277,69279,69281,69283,69285,69287,69289,69291,69293,69298&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Some pictures of the event<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2023&#8243; tab_id=&#8221;2023&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>23rd CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: left;\">In the setting of the Hotel Atlantico in Jesolo Lido (VE), the <strong>23rd City of Jesolo International Backgammon Tournament<\/strong> was held from 27 September to 1 October 2023. It was masterfully organised and directed by our Dario Zaccariotto, CNB national councillor, together with his colleagues Alfonso Sara and Cesare Nanti.<\/p>\n<p style=\"text-align: justify;\">The event was organised by the <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB \u2013 Circuito Nazionale Backgammon<\/a> in collaboration with Backgammon Club Venezia, Hotel Atlantico and ACSI &#8211; Associazione Centri Sportivi Italiani, and is also valid as the penultimate stage of the 2023 Circuit.<\/p>\n<p style=\"text-align: justify;\">There were many opportunities for enthusiasts: in addition to the tournament in three categories (Champion played with direct elimination in the &#8216;double chance&#8217; version, Intermediate with the Italo-Swiss formula, and Amateur for those who are just starting out in competitive play) there was the team tournament, the doubles tournament, the sparkling Swing, the speed tournament with tight time limits, and more. The rich schedule was appreciated by the players who flocked to Jesolo in large numbers: over 120 backgammon players threw dice on the sunny Adriatic beach for the penultimate stage of the 2023 National Circuit. Worth mentioning is the fact that people from over 20 countries, including Costa Rica, Australia and the United States, attended the tournament.<\/p>\n<p style=\"text-align: justify;\">But let us come to the record: the main tournament was won by Philippe Vouh\u00e9 from France over Antonio Anelli from Pesaro, with a score of 15 to 3. For the histrionic Frenchman also a place of honour in the speed tournament. The French were also victorious thanks to Kader Turk, who won the Open tournament, and Fraderic Bonard, who won the swing.<br \/>\nBulgarian victory in the pairs tournament, in which Nikolay Dragostinov and Atanas Tachev got the better of Laurence Sinitky and Jiri Vala, while a transnational team triumphed in the team tournament in which our Venetian team leaders Sergio Fragiacomo (captain), Massimo Trov\u00f2 and Dario De Toffoli bowed out only to the winners Sebastian Wilkinson (UK), Ricardo Malas (Spain) and Mahmoud Taha (Austria).<\/p>\n<p style=\"text-align: justify;\">Little glory for the leader of the ranking, Andrea de Zandonati from Mestre, who, despite the setback, still leads heading into the last tournament of the season.<\/p>\n<p style=\"text-align: justify;\">Now, the appointment is set for Lago di Como, where the final stage of the championship will take place in Varenna from 27 to 29 October, and Montegrotto, where the final playoffs will be held from 30 November to 3 December.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2023\/10\/Depliant_Jesolo_2023.jpg\" rel=\"lightbox[52625]\"><strong>Event schedule<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2023\/10\/Risultati-Backgammon-Jesolo-2023.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Results of the main tournaments in PDF<\/strong><\/a><\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696867070867-c9f7dfc9-702b-5&#8243; include=&#8221;69234,69236,69238,69240,69242,69246,69248,69251,69253,69255,69257,69259,69261,69263,69265,69267,69269,69271,69273,69275,69277,69279,69281,69283,69285,69287,69289,69291,69293,69298&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Some pictures of the event<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2022&#8243; tab_id=&#8221;2022&#8243;][\/vc_tta_section][vc_tta_section title=&#8221;2021&#8243; tab_id=&#8221;2021&#8243;][\/vc_tta_section][vc_tta_section title=&#8221;2020&#8243; tab_id=&#8221;2020&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>20\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto, consigliere nazionale del CNB,\u00a0ha magistralmente organizzato e diretto, assieme ai colleghi Alfonso Sara e Cesare Nanti, il <strong>20\u00b0 Torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 24 al 27 settembre 2020.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e l\u2019ACSI \u2013 Associazione Centri Sportivi Italiani.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/DEPLIANT-JESOLO-settembre-2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento<\/strong> <strong>in PDF<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Risultati-Jesolo-2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Risultati e nomi dei vincitori di ogni categoria<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761294-ad7af03c-714a-6&#8243; include=&#8221;52891,52892,52893,52894,52895,52896,52897,52898&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2019&#8243; tab_id=&#8221;2019&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>19\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto, consigliere nazionale del CNB,\u00a0ha magistralmente organizzato e diretto, assieme ai colleghi Alfonso Sara e Cesare Nanti, il <strong>19\u00b0 Torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 30 aprile al 5 maggio 2019.<\/p>\n<p style=\"text-align: left;\">L\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e l\u2019ACSI \u2013 Associazione Centri Sportivi Italiani.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Volantino-Jesolo-2019-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento<\/strong> <strong>in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761299-f039b1ab-10cc-4&#8243; include=&#8221;52886,52887,52888,52889,52882,52702&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2018&#8243; tab_id=&#8221;2018&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>18\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>18\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 26 aprile al 1\u00b0 maggio 2018.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e l\u2019ACSI \u2013 Associazione Centri Sportivi Italiani.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/BROCHURE-JESOLO-2018-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento<\/strong> <strong>in PDF<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Risultati-Jesolo-2018.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Risultati e nomi dei vincitori di ogni categoria<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761302-57dd1c55-6dee-10&#8243; include=&#8221;52874,52875,52876,52877,52878,52704&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2017&#8243; tab_id=&#8221;2017&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>17\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto, consigliere nazionale del CNB,\u00a0ha magistralmente organizzato e diretto, assieme ai colleghi Alfonso Sara e Cesare Nanti, il <strong>17\u00b0 Torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto dal 27 aprile al 1\u00b0 maggio 2017.<br \/>\nL\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e l\u2019ACSI \u2013 Associazione Centri Sportivi Italiani.<\/p>\n<p style=\"text-align: justify;\">La manifestazione ha portato all&#8217;hotel Atlantico circa 120 giocatori provenienti da tutta Europa con una buona rappresentanza femminile.<\/p>\n<p style=\"text-align: justify;\">Alle premiazioni era presente anche il presidente regionale Veneto ACSI, Rossano Nicoletto, che ha ricevuto in dono <a href=\"https:\/\/studiogiochi.com\/en\/publications\/il-grande-libro-del-backgammon-en\/\"><em>Il Grande Libro del Backgammon<\/em><\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/BROCHURE-JESOLO-2016-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento<\/strong> <strong>in PDF<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Risultati.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Risultati e nomi dei vincitori di ogni categoria<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52646&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_tta_section][vc_tta_section title=&#8221;2016&#8243; tab_id=&#8221;2016&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>16\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>16\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 22 al 25 aprile 2016.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e l\u2019ACSI \u2013 Associazione Centri Sportivi Italiani.<\/p>\n<p style=\"text-align: justify;\">Buoni risultati per il team di studiogiochi e alcune vecchie conoscenze: Dario De Toffoli e Dario Zaccariotto sono arrivati in semifinale al Double; Dario De Toffoli ha vinto il Team Tournament assieme allo svizzero Daniel Scheidiger e a Fausto Pescini; Carlo Melzi (coautore de <a href=\"https:\/\/studiogiochi.com\/en\/publications\/il-grande-libro-del-backgammon-en\/\"><em>Il Grande Libro del Backgammon<\/em><\/a>) ha vinto contro Fabrizio Lo Surdo il Main Tournament.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/BROCHURE-JESOLO-2017-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento\u00a0<\/strong><strong>i<\/strong><strong>n PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;5427&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\">Dario De Toffoli, Daniel Scheidiger e Fausto Pescini, vincitori del Team Tournament<\/h6>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;5429&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;5431&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_single_image image=&#8221;5434&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\">Carlo Melzi, vincitore del Citt\u00e0 di Jesolo, riceve il premio da Dario Zaccariotto e Alfonso Sara<\/h6>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;5436&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\">In primo piano Giuseppe Ba\u00f9 gioca con Luisa Sequeira. A suo marito Mario, recentemente scomparso, \u00e8 stato dedicato un torneo commemorativo, vinto da Fabrizio Lo Surdo.<\/h6>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;5438&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\">Scena di gioco all&#8217;Hotel Atlantico, ottima sede dell&#8217;evento<\/h6>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52863&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<h6 style=\"text-align: center;\">Foto di gruppo<\/h6>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2015&#8243; tab_id=&#8221;2015&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>15\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>15\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 30 aprile al 3 maggio 2015.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">CNB &#8211; Circuito Nazionale Backgammon<\/a>\u00a0in collaborazione con l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/BROCHURE-JESOLO-2015-IT.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52855&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_single_image image=&#8221;52859&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;52856&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;2014&#8243; tab_id=&#8221;2014&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>14\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>14\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 30 aprile al 4 maggio 2014.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon e il pi\u00f9 longevo circolo d\u2019Italia, in collaborazione con il <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">Circuito Nazionale Backgammon<\/a>, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2014.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52709&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/BROCHURE-JESOLO-ita-2014.pdf&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Il programma dell&#8217;evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2013&#8243; tab_id=&#8221;2013&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>13\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>13\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 2 al 5 maggio 2013.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon e il pi\u00f9 longevo circolo d\u2019Italia, in collaborazione con il <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">Circuito Nazionale Backgammon<\/a>, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2013.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761314-b9b6bee4-6b36-10&#8243; include=&#8221;54061,54063,54060,54062,54064,54066,54067,54068,54065,54069,54070,54071&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2012&#8243; tab_id=&#8221;2012&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>12\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>12\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 10 al 13 maggio 2012.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon e il pi\u00f9 longevo circolo d\u2019Italia, in collaborazione con il <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">Circuito Nazionale Backgammon<\/a>, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2012.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761321-09f3b78a-fd11-1&#8243; include=&#8221;54057,54041,54054,54055,54058,54059,54056,54042,54043,54044,54045,54046,54047,54048,54049,54050,54051,54052&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2011&#8243; tab_id=&#8221;2011&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>11\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione dell&#8217;<strong>11\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 6 all&#8217;8 maggio 2011.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon e il pi\u00f9 longevo circolo d\u2019Italia, in collaborazione con il <a href=\"http:\/\/www.cnbackgammon.eu\/home.html\">Circuito Nazionale Backgammon<\/a>, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2011.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][\/vc_tta_section][vc_tta_section title=&#8221;2010&#8243; tab_id=&#8221;2010&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>10\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>10\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 6 al 9 maggio 2010.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il\u00a0Circuito Nazionale Backgammon, il Comune di Jesolo, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali e SkillClub.<\/p>\n<p style=\"text-align: justify;\">Partecipante d\u2019eccezione al torneo del decennale: tra i partecipanti nella categoria Champion infatti c\u2019era Theo Kypri, la controfigura di Johnny Depp per le riprese di <em>The Tourist<\/em> (che gi\u00e0 ha prestato il suo fisico alla star nella saga dei pirati ai Caraibi nonch\u00e9 a Banderas interprete di Zorro).<\/p>\n<p style=\"text-align: justify;\">Molte le occasioni per gli appassionati: oltre al torneo in due categorie (Champion giocata ad eliminazione diretta e Amateur con gironi all\u2019italiana) s\u2019\u00e8 disputato il torneo double nella modalit\u00e0 1 doppio a consultazione &#8211; 2 singoli, lo spumeggiante Swing (una sorta di sistema italo-svizzero a poste crescenti), il torneo Uisp-Backgammon per Tutti, lo SpeedyGammon (con tempo ridotto per l\u2019intera partita, un po\u2019 come il \u201csemilampo\u201d per gli scacchi) e il FlashGammon (con tempo risibile per l\u2019intera partita, un po\u2019 come il \u201clampo\u201d per gli scacchi) nonch\u00e9 altri eventi collaterali. Il programma ricco \u00e8 stato apprezzato dai giocatori che si sono riversati a Jesolo numerosi (circa un centinaio) malgrado il weekend tutt\u2019altro che assolato.<\/p>\n<p style=\"text-align: justify;\">Ma veniamo alla cronaca del torneo: malgrado la presenza di molti forti giocatori da vari stati europei, nel torneo principale finale tutta italiana tra Massimiliano Calusio di Milano e Vincenzo Di Clemente di Napoli, condotta dal giocatore meneghino tutto il tempo e terminata a suo favore 15 a 9.<\/p>\n<p style=\"text-align: justify;\">Parla italo-rumeno invece la categoria Amateur, dove s\u2019\u00e8 imposto il veronese d\u2019origine danubiana Viorel Popa sulla brianzola Annalisa Agosti.<\/p>\n<p style=\"text-align: justify;\">Poca gloria invece per i giocatori del Backgammon Club Venezia, che nelle prime due tappe avevano ottenuto ottimi risultati tanto da imporre il proprio circolo quale migliore d\u2019Italia.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Depliant-Jesolo-2010.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761331-766a73c9-a2df-5&#8243; include=&#8221;52840,52841,52842,52843,52844,52845&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2009&#8243; tab_id=&#8221;2009&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>9\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del\u00a0<strong>9\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 23 al 26 aprile 2009.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon, in collaborazione con il\u00a0Circuito Nazionale Backgammon, il Comune di Jesolo, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Volantino-Jesolo-2009.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761334-55579414-5121-9&#8243; include=&#8221;52815,52816,52817,52818,52819,52820,52821,52822,52823,52824,52825,52826,52827,52828,52829,52830,52831,52832&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2008&#8243; tab_id=&#8221;2008&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>8\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione dell&#8217;<strong>8\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 24 al 27 aprile 2008.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, da oltre un ventennio il maggior sodalizio veneto di Backgammon, in collaborazione con il\u00a0Circuito Nazionale Backgammon, il Comune di Jesolo, l\u2019Hotel Atlantico e la UISP \u2013 Lega Sport e Giochi Tradizionali.<\/p>\n<p style=\"text-align: justify;\">In aggiunta al consueto programma, alcune sessioni di <em>Backgammon on the Beach, <\/em>vale a dire maestri che direttamente nella spiaggia antistante l\u2019albergo hanno insegnato gratuitamente a chiunque lo desiderasse i primi rudimenti di questo gioco pluri-millenario.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2008.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761343-199d1fce-eab6-1&#8243; include=&#8221;52798,52799,52800,52801,52802,52803,52804,52805,52806,52807,52808,52809&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2007&#8243; tab_id=&#8221;2007&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>7\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del <strong>7\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto all\u2019Hotel Atlantico di Jesolo (VE) dal 27 aprile al 1 maggio 2007.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il lungimirante Comune di Jesolo, l\u2019Hotel Atlantico, la UISP \u2013 Lega Sport e Giochi Tradizionali, l\u2019agenzia Trad&amp;co e tutti gli organizzatori del Circuito Nazionale 2007.<\/p>\n<p style=\"text-align: justify;\">Molte le occasioni per gli appassionati: oltre al torneo in due categorie (Champion giocata ad eliminazione diretta e Intermediate con formula italo-svizzera) s\u2019\u00e8 disputato il torneo a squadre, il torneo di doppio nella modalit\u00e0 della Coppa Davis di tennis (2 singoli, 1 doppio a consultazione, 2 singoli), lo spumeggiante Swing (una sorta di sistema italo-svizzero a poste crescenti) nonch\u00e9 si sono svolte le finali del Campionato Veneto 2006-07. Il programma ricco \u00e8 stato apprezzato dai giocatori che si sono riversati numerosi a Jesolo: oltre 80 giocatori diversi hanno lanciato dadi nell\u2019assolata spiaggia adriatica in occasione della seconda tappa del Circuito Nazionale 2007!<\/p>\n<p style=\"text-align: justify;\">Ma veniamo alla cronaca: malgrado la presenza di giocatori da vari stati europei, nel torneo principale finale tutta Backgammon Club Venezia tra Stefano Boni e Andrea de Zandonati. Andrea prima ha giocato al gatto e il topo, lasciando sempre qualche punto di vantaggio e l\u2019illusione della vittoria all\u2019amico\/avversario Stefano, poi ha imposto nel finale di partita il proprio ritmo e ha piegato le resistenze di Boni. Da notare che il bravo Andrea s\u2019era pure aggiudicato il torneo di swing disputatosi il sabato sera.<\/p>\n<p style=\"text-align: justify;\">Parla BCVE anche la categoria Intermediate dove s\u2019\u00e8 imposto il mestrino Cesare Nanti su Stefano Sinopoli (il dominatore della regular season del campionato veneto): un tributo al glorioso sodalizio che proprio a Jesolo ha fatto festa per il proprio ventesimo compleanno!<\/p>\n<p style=\"text-align: justify;\">Da segnalare poi l\u2019ottima prestazione del milanese Carlo Melzi, vincitore del Torneo Atlantico e \u2013 in coppa con Claudio Cantoni \u2013 della Coppia Davis e del tedesco Chrisitian Liebe-Harkott capace di bissare nel team il successo dello scorso anno.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2007.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761349-d1cdd7ff-7f51-0&#8243; include=&#8221;52768,52769,52770,52771,52772,52773,52774,52775,52776,52777,52778,52779,52780,52781,52784,52785,52786,52787,52789,52790,52791,52792,52793,52794&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2006&#8243; tab_id=&#8221;2006&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>6\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Come ogni anno il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del <strong>6\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto nella cornice dell&#8217;Hotel Marina di Jesolo (VE) dal 28 aprile al 1 maggio 2006.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato\u00a0organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, gli Hotel Marina e Adlon, studiogiochi, la UISP \u2013 Lega Sport e Giochi Tradizionali, l\u2019agenzia Easyevents,\u00a0 Backgammon.it e tutti gli organizzatori del Circuito Nazionale 2006.<\/p>\n<p style=\"text-align: justify;\">Molte le novit\u00e0 nella manifestazione di quest\u2019anno: il torneo a squadre ha coinvolto molto di pi\u00f9 i giocatori in una multisfida \u201ctutti contro tutti\u201d e non il solito \u201cuno per squadra contro uno per squadra\u201d, il torneo di doppio s\u2019\u00e8 svolto per la prima volta in un torneo internazionale secondo le modalit\u00e0 della Coppa Davis di tennis (2 singoli, 1 doppio a consultazione, 2 singoli), s\u2019\u00e8 sperimentato dal vivo lo Swing, una sorta di sistema italo-svizzero a poste crescenti, si sono svolte le finali del Campionato Veneto 2005-06. Il programma ricco \u00e8 stato apprezzato dai giocatori che si sono riversati numerosi a Jesolo: oltre 100 giocatori diversi, provenienti persino dal Messico, hanno preso parte alla manifestazione valida quale seconda tappa del Circuito Nazionale 2006!<\/p>\n<p style=\"text-align: justify;\">Ma veniamo alla cronaca: nel torneo principale vittoria schiacciante dell\u2019austrico Wolfgang Haas che con un perentorio 15-1 ha piegato il torinese Giorgio Castellano, recente vincitore al torneo di Copenaghen (uno dei pi\u00f9 importanti e frequentati al mondo). Da notare che il forte viennese faceva parte della squadra finalista nel torneo a squadre e del doppio semifinalista nel <em>Coppia Davis<\/em>. Onore pure al veneziano Sergio Fragiacomo, il campione in carica che s\u2019arreso solo in semifinale contro Haas.<\/p>\n<p style=\"text-align: justify;\">Parla veneto invece la categoria Intermediate dove s\u2019\u00e8 imposto il vicentino Alvin Anderson sul sandonatese Silvio Riccobon, il quale a sua volta in semifinale aveva sconfitto il veronese Florin Popa.<\/p>\n<p style=\"text-align: justify;\">Grazie alla brillante prestazione, Giorgio Castellano balza al comando della classifica del Circuito\u00a0 Nazionale 2006 con 68 punti; alle sue spalle l\u2019austriaco Peter Winkler (66), precedente leader, mentre pi\u00f9 staccati gli evergreen Carlo Facchetti (56) e Guido Flamigni (54).<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2006.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761360-fc95b978-d4c0-5&#8243; include=&#8221;52753,52755,52754,52756,52757,52758,52759,52760,52761,52762,52763,52764&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell\u2019evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2005&#8243; tab_id=&#8221;2005&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>5\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del <strong>5\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto nella magnifica cornice del Park Hotel Brasilia di Jesolo (VE) dal 28 aprile al 1 maggio 2005.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato organizzato dal Circolo Piccadilly e dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, il Park Hotel Brasilia e studiogiochi.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2005.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell\u2019evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_media_grid element_width=&#8221;2&#8243; grid_id=&#8221;vc_gid:1696866761366-0ae3cb98-cd95-0&#8243; include=&#8221;52731,52732,52733,52734,52735,52736,52737,52738,52739,52740,52741,52742,52743,52744,52745,52746,52747,52748&#8243;][vc_column_text]\n<p style=\"text-align: center;\">Alcune foto dell&#8217;evento<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2004&#8243; tab_id=&#8221;2004&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>4\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all\u2019organizzazione e alla gestione del <strong>4\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto nella magnifica cornice dell\u2019Hotel Casa Bianca al Mare di Jesolo (VE) dal 29 aprile al 2 maggio 2004.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato organizzato dal Circolo Piccadilly e dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, l\u2019Hotel Casa Bianca al Mare e studiogiochi.<\/p>\n<p style=\"text-align: justify;\">Il livello dei giocatori \u00e8 stato altissimo: basti pensare che era presente il californiano campione olimpionico Bob Wachtel. Complessivamente hanno preso parte 93 diversi giocatori, provenienti da ben 15 nazioni: Italia, Armenia, Austria, Bulgaria, Croazia, Danimarca, Germania, Hong Kong, Olanda, Portogallo, Slovenia, Spagna, Stati Uniti, Svizzera e Thailandia.<\/p>\n<p style=\"text-align: justify;\">Nel torneo principale vittoria schiacciante del fortissimo Lars Trabolt che con un perentorio 13-0 ha piegato l\u2019austriaco Andreas Fischer, un affezionato frequentatore dei tornei jesolani. Gli italiani si sono per\u00f2 presi la rivincita nel Trofeo casa Bianca al mare: in una finale tricolore il veneziano Dario De Toffoli ha sconfitto il milanese Vincenzo Riceputi.<\/p>\n<p style=\"text-align: justify;\">Anche i giocatori veneti qualche soddisfazione se la sono tolta: oltre al citato Dario De Toffoli, si segnala soprattutto l\u2019affermazione nel torneo a squadre del Piccadilly Team, composto da Lorenzo Lagan\u00e0, Valerio Scremin e dal portoghese Mario Sequeira; parla veneto anche la categoria intermediate del Citt\u00e0 di Jesolo: a parte il vincitore armeno, gloria per i vicentini Antonio Sinigaglia Alvise Checchini e Lorenzo Borsoi e per i veneziani Stefano Chiosi e Sandro Mescola.<\/p>\n<p style=\"text-align: justify;\">Grosso successo ha avuto poi la trasmissione online della finale commentata da un pool di giocatori: si trattava di una seconda volta a livello mondiale!<br \/>\nAnche quest\u2019anno la chiave del successo \u00e8 stata la fattiva collaborazione fra il Backgammon Club Venezia e il circolo Piccadilly, il lungimirante Comune di Jesolo e l\u2019Hotel Casa Bianca al Mare che ha saputo coniugare al meglio qualit\u00e0 e disponibilit\u00e0.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2022\/01\/Depliant-Jesolo-2004.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell&#8217;evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52726&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Sara Casarin con Andrea de Zandonati, finalista del torneo Double<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52727&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Sara Casarin con Andreas e Alexander Reichel, finalisti del torneo a squadre<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2003&#8243; tab_id=&#8221;2003&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>3\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto,\u00a0in qualit\u00e0 di presidente del Backgammon Club Venezia,\u00a0ha collaborato all&#8217;organizzazione e alla gestione del <strong>3\u00b0\u00a0torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto nella magnifica cornice dell&#8217;Hotel Casa Bianca al Mare di Jesolo (VE) dall&#8217;1 al 4 maggio 2003.<\/p>\n<p style=\"text-align: justify;\">L&#8217;evento \u00e8 stato organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, l\u2019Hotel Casa Bianca al Mare e studiogiochi.<\/p>\n<p style=\"text-align: justify;\">Sempre pi\u00f9 internazionale l\u2019atmosfera della manifestazione che assieme al backgammon proponeva Gin Rummy e altri giochi. Complessivamente vi hanno preso parte 104 diversi giocatori, provenienti da ben 14 nazioni: Italia, Armenia, Austria, Brasile, Bulgaria, Croazia, Danimarca, Germania, Polonia, Portogallo, Russia, Serbia-Montenegro, Slovenia e Svizzera.<\/p>\n<p style=\"text-align: justify;\">E la vittoria nel torneo principale \u00e8 arrisa al simpatico svizzero (di madre italiana) Daniel Bruni, un affezionato frequentatore dei tornei jesolani che ha avuto la meglio in finale sul bulgaro Andr\u00e8 Markov. Gli italiani si sono per\u00f2 presi la rivincita nel Trofeo casa Bianca al mare con il bergamasco Matteo Di Napoli che ha avuto la meglio sul fortissimo tedesco Christian Liebe Harkort.<\/p>\n<p style=\"text-align: justify;\">Anche i giocatori veneti qualche soddisfazione se la sono tolta. In primis la padovana Franca Boscari, davvero in stato di grazia, si \u00e8 brillantemente aggiudicata il torneo principale della categoria intermediate; e poi il \u201cLagalaga Team\u201d, composto da Lorenzo Lagan\u00e0, Valerio Scremin e dal portoghese Mario Sequeira, ha vinto il torneo a squadre.<\/p>\n<p style=\"text-align: justify;\">Vincitori e vinti tutti contenti per la riuscita del torneo che accanto ad un sano agonismo ha proposto anche quest\u2019anno un\u2019atmosfera amichevole e vacanziera. La chiave del successo \u00e8 stata la fattiva collaborazione fra il Backgammon Club Venezia, il lungimirante Comune di Jesolo e l\u2019Hotel Casa Bianca al Mare che ha saputo coniugare al meglio qualit\u00e0 e disponibilit\u00e0.<\/p>\n<p><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Depliant-Jesolo-2003.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programma dell&#8217;evento in PDF<\/strong><\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52719&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Lo staff<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52720&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Dario De Toffoli con Magda Casarin e i finalisti del torneo Double Andreas e Alexander Reichel<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52722&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Dario De Toffoli con Magda Casarin e i vincitori del torneo Double Elmar Kofler e Laura Ziliani<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52721&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Dario De Toffoli con Magda Casarin e la vincitrice del torneo Intermediate Franca Boscari<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2002&#8243; tab_id=&#8221;2002&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>2\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto ha collaborato all&#8217;organizzazione e alla gestione del <strong>2\u00b0 torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>,\u00a0che si \u00e8 svolto nel Palazzo del Turismo di Jesolo (VE) dal 25 al 28 aprile 2002.<\/p>\n<p style=\"text-align: justify;\">L&#8217;evento \u00e8 stato organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, l\u2019Hotel Casa Bianca al Mare e studiogiochi.<\/p>\n<p style=\"text-align: justify;\">Ribaltato il detto \u201cNemo propheta in patria\u201d perch\u00e9 la finale \u00e8 stata giocata tra due appartenenti al circolo veneziano: la vittoria \u00e8 andata allo sloveno Dami Plesec sul mestrino Andrea de Zandonati (che da ben 16 anni si sobbarca l\u2019onere di tenere aggiornate le classifiche del circolo!).<\/p>\n<p style=\"text-align: justify;\">Gloria anche per molti giocatori del Backgammon Club Venezia: nel torneo a coppie il duo Piergiorgio D\u2019Ancona-Girolamo Castiglioni ha ceduto solo in finale agli onnipresenti portoghesi Laura e Mario Sequeira, Magda Casarin faceva parte della squadra vincitrice nel torneo a squadre, Franco Di Natale si \u00e8 aggiudicato il Kick Off, Lorenzo Lagan\u00e0 (il brillante presidente) il torneo di gin rummy.<\/p>\n<p style=\"text-align: justify;\">Vincitori e vinti tutti contenti per la riuscita del torneo che accanto ad un sano agonismo ha proposto anche quest\u2019anno un\u2019atmosfera amichevole e vacanziera. La chiave del successo \u00e8 stata la fattiva collaborazione fra il Club organizzatore, il lungimirante Comune di Jesolo e l\u2019Hotel Casa Bianca al Mare che ospitava i giocatori.<\/p>\n<p style=\"text-align: justify;\">Complessivamente hanno partecipato ai vari eventi pi\u00f9 di 100 diversi giocatori, provenienti da 8 nazioni.<\/p>\n<p><strong><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Depliant-Jesolo-2001.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Programma dell&#8217;evento in PDF<\/a><\/strong>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52713&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<p style=\"text-align: center;\">I portoghesi Laura e Mario Sequeira<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52715&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Il vincitore sloveno Dami Plesec<\/p>\n[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52714&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Il podio<\/p>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;2001&#8243; tab_id=&#8221;2001&#8243;][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>1\u00b0 CITT\u00c0 DI JESOLO<\/strong><\/h2>\n<p style=\"text-align: justify;\">Il nostro Dario Zaccariotto ha collaborato all&#8217;organizzazione e alla gestione del <strong>1\u00b0 torneo di Backgammon Citt\u00e0 di Jesolo<\/strong>, che si \u00e8 svolto nel Palazzo del Turismo di Jesolo (VE) dal 18 al 20 maggio 2001.<\/p>\n<p style=\"text-align: justify;\">L&#8217;evento \u00e8 stato organizzato dal Backgammon Club Venezia, uno dei sodalizi italiani pi\u00f9 rappresentativi e attivi, in collaborazione con il Comune di Jesolo, l\u2019Hotel Casa Bianca al Mare e studiogiochi.<\/p>\n<p style=\"text-align: justify;\">La vittoria \u00e8 andata al forlivese Guido Flamigni, che, dopo aver faticato moltissimo nei quarti di finale contro lo sloveno Dami Plesec (13 a 12), si \u00e8 imposto invece facilmente in semifinale sul bolognese Luciano Rubbi e in finale sul milanese Francesco Mauri. La previsione di vittoria \u00e8 stata dunque rispettata: Flamigni era considerato assieme al croato Markotic ed ai tedeschi K\u00f6rner e Reinhardt (vincitori invece nel torneo a squadre) uno dei favoriti per il successo finale.<\/p>\n<p style=\"text-align: justify;\">Gloria anche per molti giocatori del Backgammon Club Venezia: Andrea de Zandonati (che da ben 15 anni si sobbarca l\u2019onere di tenere aggiornate le classifiche del circolo!) si \u00e8 aggiudicato il Trofeo Casa Bianca al Mare; Ennio Gioppato ha trionfato nella categoria \u201cIntermediate\u201d e, assieme a Franco di Natale e Mauro Da Lio, ha raggiunto la finale nel torneo a squadre; Alfonso Sara ha fatto parte del doppio vincitore del torneo a coppie mentre Franca Boscari e Lorenzo Lagan\u00e0 (l\u2019indefesso e intraprendente presidente) hanno costituito il doppio finalista.<\/p>\n<p style=\"text-align: justify;\">Brillante prestazione infine dell\u2019evergreen Carlo Facchetti, da pi\u00f9 di vent\u2019anni ai vertici del backgammon nazionale: per lui successo con il gi\u00e0 citato Alfonso Sara nel torneo a coppie e finale nel Trofeo Casa Bianca al Mare.<\/p>\n<p style=\"text-align: justify;\">Vincitori e vinti tutti contenti per la riuscita del torneo che accanto ad un sano agonismo ha proposto un\u2019atmosfera amichevole e vacanziera. La chiave del successo \u00e8 stata la fattiva collaborazione fra il Club organizzatore, il lungimirante Comune di Jesolo e l\u2019Hotel Casa Bianca al Mare che ospitava i giocatori. Un ringraziamento anche all\u2019Iper Backgammon Association, che ha patrocinato l\u2019iniziativa.<\/p>\n<p style=\"text-align: justify;\">Complessivamente hanno partecipato ai vari eventi circa 80 diversi giocatori, provenienti da 6 nazioni.<\/p>\n<p><strong><a href=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2021\/10\/Depliant-Jesolo-2001.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Programma dell&#8217;evento in PDF<\/a><\/strong>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;52712&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]\n<p style=\"text-align: center;\">Il Palazzo del Turismo di Jesolo<\/p>\n[\/vc_column_text][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column width=\"1\/4\" el_class=\"download\"][vc_single_image image=\"3342\" img_size=\"full\"][\/vc_column][vc_column width=\"3\/4\"][vc_tta_tabs][vc_tta_section title=\"Citt\u00e0 di Jesolo\" tab_id=\"citta-di-jesolo\"][vc_column_text] 23rd CITT\u00c0 DI JESOLO In the setting of the Hotel [...]","protected":false},"author":9,"featured_media":0,"parent":3703,"menu_order":40,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-52625","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Citt\u00e0 di Jesolo - studiogiochi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citt\u00e0 di Jesolo - studiogiochi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/\" \/>\n<meta property=\"og:site_name\" content=\"studiogiochi\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T15:58:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/\",\"url\":\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/\",\"name\":\"Citt\u00e0 di Jesolo - studiogiochi\",\"isPartOf\":{\"@id\":\"https:\/\/studiogiochi.com\/#website\"},\"datePublished\":\"2021-10-13T11:55:30+00:00\",\"dateModified\":\"2023-10-09T15:58:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/studiogiochi.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Backgammon\",\"item\":\"https:\/\/studiogiochi.com\/en\/backgammon\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Citt\u00e0 di Jesolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/studiogiochi.com\/#website\",\"url\":\"https:\/\/studiogiochi.com\/\",\"name\":\"studiogiochi\",\"description\":\"35 ANNI DI GIOCHI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/studiogiochi.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citt\u00e0 di Jesolo - studiogiochi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/","og_locale":"en_US","og_type":"article","og_title":"Citt\u00e0 di Jesolo - studiogiochi","og_url":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/","og_site_name":"studiogiochi","article_modified_time":"2023-10-09T15:58:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/","url":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/","name":"Citt\u00e0 di Jesolo - studiogiochi","isPartOf":{"@id":"https:\/\/studiogiochi.com\/#website"},"datePublished":"2021-10-13T11:55:30+00:00","dateModified":"2023-10-09T15:58:33+00:00","breadcrumb":{"@id":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/studiogiochi.com\/en\/backgammon\/citta-di-jesolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studiogiochi.com\/en\/"},{"@type":"ListItem","position":2,"name":"Backgammon","item":"https:\/\/studiogiochi.com\/en\/backgammon\/"},{"@type":"ListItem","position":3,"name":"Citt\u00e0 di Jesolo"}]},{"@type":"WebSite","@id":"https:\/\/studiogiochi.com\/#website","url":"https:\/\/studiogiochi.com\/","name":"studiogiochi","description":"35 ANNI DI GIOCHI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studiogiochi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/pages\/52625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/comments?post=52625"}],"version-history":[{"count":5,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/pages\/52625\/revisions"}],"predecessor-version":[{"id":69387,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/pages\/52625\/revisions\/69387"}],"up":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/pages\/3703"}],"wp:attachment":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/media?parent=52625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}