{"id":44612,"date":"2019-10-16T10:03:26","date_gmt":"2019-10-16T08:03:26","guid":{"rendered":"https:\/\/www.studiogiochi.com\/2019\/10\/dal-premio-archimede-agli-scaffali\/"},"modified":"2019-10-16T10:20:55","modified_gmt":"2019-10-16T08:20:55","slug":"dal-premio-archimede-agli-scaffali","status":"publish","type":"post","link":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/","title":{"rendered":"From Premio Archimede to the stores"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>October 2019: already 48 games presented at the Premio Archimede and published&#8230; and 10 more are under contract with international publishers: they are coming in stores in the next months. Let&#8217;s find out which ones&#8230;<\/p>\n","protected":false},"author":9,"featured_media":44613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[17],"tags":[],"class_list":["post-44612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>From Premio Archimede to the stores - studiogiochi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"From Premio Archimede to the stores - studiogiochi\" \/>\n<meta property=\"og:description\" content=\"October 2019: already 48 games presented at the Premio Archimede and published... and 10 more are under contract with international publishers: they are coming in stores in the next months. Let&#039;s find out which ones...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\" \/>\n<meta property=\"og:site_name\" content=\"studiogiochi\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T08:03:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T08:20:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristiana.giuriato@studiogiochi.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristiana.giuriato@studiogiochi.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\"},\"author\":{\"name\":\"cristiana.giuriato@studiogiochi.com\",\"@id\":\"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a\"},\"headline\":\"From Premio Archimede to the stores\",\"datePublished\":\"2019-10-16T08:03:26+00:00\",\"dateModified\":\"2019-10-16T08:20:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\"},\"wordCount\":6,\"image\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\",\"url\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\",\"name\":\"From Premio Archimede to the stores - studiogiochi\",\"isPartOf\":{\"@id\":\"https:\/\/studiogiochi.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg\",\"datePublished\":\"2019-10-16T08:03:26+00:00\",\"dateModified\":\"2019-10-16T08:20:55+00:00\",\"author\":{\"@id\":\"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a\"},\"breadcrumb\":{\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage\",\"url\":\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg\",\"contentUrl\":\"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg\",\"width\":1440,\"height\":950},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/studiogiochi.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"From Premio Archimede to the stores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/studiogiochi.com\/#website\",\"url\":\"https:\/\/studiogiochi.com\/\",\"name\":\"studiogiochi\",\"description\":\"35 ANNI DI GIOCHI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/studiogiochi.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a\",\"name\":\"cristiana.giuriato@studiogiochi.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g\",\"caption\":\"cristiana.giuriato@studiogiochi.com\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"From Premio Archimede to the stores - studiogiochi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/","og_locale":"en_US","og_type":"article","og_title":"From Premio Archimede to the stores - studiogiochi","og_description":"October 2019: already 48 games presented at the Premio Archimede and published... and 10 more are under contract with international publishers: they are coming in stores in the next months. Let's find out which ones...","og_url":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/","og_site_name":"studiogiochi","article_published_time":"2019-10-16T08:03:26+00:00","article_modified_time":"2019-10-16T08:20:55+00:00","og_image":[{"width":1440,"height":950,"url":"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg","type":"image\/jpeg"}],"author":"cristiana.giuriato@studiogiochi.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cristiana.giuriato@studiogiochi.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#article","isPartOf":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/"},"author":{"name":"cristiana.giuriato@studiogiochi.com","@id":"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a"},"headline":"From Premio Archimede to the stores","datePublished":"2019-10-16T08:03:26+00:00","dateModified":"2019-10-16T08:20:55+00:00","mainEntityOfPage":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/"},"wordCount":6,"image":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage"},"thumbnailUrl":"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/","url":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/","name":"From Premio Archimede to the stores - studiogiochi","isPartOf":{"@id":"https:\/\/studiogiochi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage"},"image":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage"},"thumbnailUrl":"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg","datePublished":"2019-10-16T08:03:26+00:00","dateModified":"2019-10-16T08:20:55+00:00","author":{"@id":"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a"},"breadcrumb":{"@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#primaryimage","url":"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg","contentUrl":"https:\/\/studiogiochi.com\/files\/studiogiochi.com\/2019\/10\/Archimede-giochi-in-pubblicazione.jpg","width":1440,"height":950},{"@type":"BreadcrumbList","@id":"https:\/\/studiogiochi.com\/en\/2019\/10\/dal-premio-archimede-agli-scaffali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studiogiochi.com\/en\/"},{"@type":"ListItem","position":2,"name":"From Premio Archimede to the stores"}]},{"@type":"WebSite","@id":"https:\/\/studiogiochi.com\/#website","url":"https:\/\/studiogiochi.com\/","name":"studiogiochi","description":"35 ANNI DI GIOCHI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studiogiochi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/studiogiochi.com\/#\/schema\/person\/65c45c95de448afd1f5017d93f77ce0a","name":"cristiana.giuriato@studiogiochi.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82ea4d44b816d1235e7839a274db7677393ee5cb1afcdb89417c8a0834c1f952?s=96&d=mm&r=g","caption":"cristiana.giuriato@studiogiochi.com"}}]}},"_links":{"self":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/posts\/44612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/comments?post=44612"}],"version-history":[{"count":2,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/posts\/44612\/revisions"}],"predecessor-version":[{"id":44615,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/posts\/44612\/revisions\/44615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/media\/44613"}],"wp:attachment":[{"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/media?parent=44612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/categories?post=44612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/studiogiochi.com\/en\/wp-json\/wp\/v2\/tags?post=44612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}